{"id":83,"date":"2023-03-31T10:50:25","date_gmt":"2023-03-31T10:50:25","guid":{"rendered":"https:\/\/webs.anubissolutions.es\/newdamarl\/producto\/elevador-de-coches-2-columnas-para-taller-dm4-0t-2\/"},"modified":"2025-03-05T10:20:54","modified_gmt":"2025-03-05T10:20:54","slug":"elevador-de-coches-2-columnas-para-taller-dm4-0t-2","status":"publish","type":"product","link":"https:\/\/www.damarl.com\/en\/product\/elevador-de-coches-2-columnas-para-taller-dm4-0t-2\/","title":{"rendered":"2 Post Semi-Base  Lift 4T | DM4.0T\/2"},"content":{"rendered":"<p>Single and three-phase electro-hydraulic two-column lift<\/p>\r\n<p><strong>Description:<\/strong><\/p>\r\n<p>\r\n\r\n<\/p>\r\n<ul>\r\n<li>For surface installation<\/li>\r\n<li>Semibase<\/li>\r\n<li>2 hydraulic cylinders + chain<\/li>\r\n<li>Synchronised steel rope<\/li>\r\n<li>Lowering solenoid valve<\/li>\r\n<li>Electromagnetic safety locking system<\/li>\r\n<li>Maximum height limit switch<\/li>\r\n<li>3-stage symmetrical arms<\/li>\r\n<li>80 mm Extension pads<\/li>\r\n<\/ul>\r\n<p><strong>Technical data:<\/strong><\/p>\r\n\r\n\r\n\r\n<ul>\r\n<li>Capacity: 4000kg<\/li>\r\n<li>Lifting range: 110 \u2013 1975 mm<\/li>\r\n<li>Lifting time: 45 s<\/li>\r\n<li>Lowering time: 45 s<\/li>\r\n<li>Power: 400V\/3ph\/50Hz\/2.2KW \/ 230V\/1ph\/50Hz\/2.2KW<\/li>\r\n<li>Weight: 623 kg<\/li>\r\n<\/ul>\r\n\r\n\r\n\r\n\r\n\r\n<p><strong>Accessories included:<\/strong><\/p>\r\n<ul>\r\n<li>4 x Rubber pads<\/li>\r\n<li>4 x Extension pads 70 mm<\/li>\r\n<li>4 x Extension 100 mm<\/li>\r\n<\/ul>","protected":false},"excerpt":{"rendered":"<p class=\"ficha-download\"><a href=\"https:\/\/www.damarl.com\/wp-content\/uploads\/2024\/09\/Elevador_2_columnas_DM4.0T_2_230V_400V_catalogo_dama_2024_pag48.pdf\">Download File<\/a><\/p>","protected":false},"featured_media":6831,"template":"","meta":{"_acf_changed":false,"_kad_post_transparent":"default","_kad_post_title":"","_kad_post_layout":"default","_kad_post_sidebar_id":"","_kad_post_content_style":"default","_kad_post_vertical_padding":"default","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":""},"product_brand":[],"product_cat":[109,119,117,81],"product_tag":[],"class_list":{"0":"post-83","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-elevadores","7":"product_cat-elevadores-de-2-columnas","8":"product_cat-elevadores-de-taller","9":"product_cat-maquinaria","11":"first","12":"instock","13":"product-type-simple","14":"entry","15":"content-bg","16":"loop-entry"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.damarl.com\/en\/wp-json\/wp\/v2\/product\/83","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.damarl.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.damarl.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.damarl.com\/en\/wp-json\/wp\/v2\/media\/6831"}],"wp:attachment":[{"href":"https:\/\/www.damarl.com\/en\/wp-json\/wp\/v2\/media?parent=83"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.damarl.com\/en\/wp-json\/wp\/v2\/product_brand?post=83"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.damarl.com\/en\/wp-json\/wp\/v2\/product_cat?post=83"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.damarl.com\/en\/wp-json\/wp\/v2\/product_tag?post=83"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}